{"id":495,"date":"2020-08-20T13:04:29","date_gmt":"2020-08-20T13:04:29","guid":{"rendered":"http:\/\/miguelpons.net\/english\/wp-content\/uploads\/2020\/08\/Cartel-La-Gran-Timba.jpeg"},"modified":"2020-08-20T14:58:51","modified_gmt":"2020-08-20T14:58:51","slug":"cartel-la-gran-timba","status":"inherit","type":"attachment","link":"http:\/\/miguelpons.net\/english\/my-films\/cartel-la-gran-timba\/","title":{"rendered":"La Gran Timba (2006)"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-495","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/miguelpons.net\/english\/wp-content\/uploads\/2020\/08\/Cartel-La-Gran-Timba.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"http:\/\/miguelpons.net\/english\/wp-content\/uploads\/2020\/08\/Cartel-La-Gran-Timba-225x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"http:\/\/miguelpons.net\/english\/wp-content\/uploads\/2020\/08\/Cartel-La-Gran-Timba-225x300.jpeg 225w, http:\/\/miguelpons.net\/english\/wp-content\/uploads\/2020\/08\/Cartel-La-Gran-Timba-768x1024.jpeg 768w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2160,"height":2880,"file":"2020\/08\/Cartel-La-Gran-Timba.jpeg","sizes":{"thumbnail":{"file":"Cartel-La-Gran-Timba-150x150.jpeg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"http:\/\/miguelpons.net\/english\/wp-content\/uploads\/2020\/08\/Cartel-La-Gran-Timba-150x150.jpeg"},"medium":{"file":"Cartel-La-Gran-Timba-225x300.jpeg","width":225,"height":300,"mime_type":"image\/jpeg","source_url":"http:\/\/miguelpons.net\/english\/wp-content\/uploads\/2020\/08\/Cartel-La-Gran-Timba-225x300.jpeg"},"medium_large":{"file":"Cartel-La-Gran-Timba-768x1024.jpeg","width":768,"height":1024,"mime_type":"image\/jpeg","source_url":"http:\/\/miguelpons.net\/english\/wp-content\/uploads\/2020\/08\/Cartel-La-Gran-Timba-768x1024.jpeg"},"large":{"file":"Cartel-La-Gran-Timba-768x1024.jpeg","width":768,"height":1024,"mime_type":"image\/jpeg","source_url":"http:\/\/miguelpons.net\/english\/wp-content\/uploads\/2020\/08\/Cartel-La-Gran-Timba-768x1024.jpeg"},"post-thumbnail":{"file":"Cartel-La-Gran-Timba-672x372.jpeg","width":672,"height":372,"mime_type":"image\/jpeg","source_url":"http:\/\/miguelpons.net\/english\/wp-content\/uploads\/2020\/08\/Cartel-La-Gran-Timba-672x372.jpeg"},"twentyfourteen-full-width":{"file":"Cartel-La-Gran-Timba-1038x576.jpeg","width":1038,"height":576,"mime_type":"image\/jpeg","source_url":"http:\/\/miguelpons.net\/english\/wp-content\/uploads\/2020\/08\/Cartel-La-Gran-Timba-1038x576.jpeg"},"full":{"file":"Cartel-La-Gran-Timba.jpeg","width":2160,"height":2880,"mime_type":"image\/jpeg","source_url":"http:\/\/miguelpons.net\/english\/wp-content\/uploads\/2020\/08\/Cartel-La-Gran-Timba.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"1597883077","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":491,"source_url":"http:\/\/miguelpons.net\/english\/wp-content\/uploads\/2020\/08\/Cartel-La-Gran-Timba.jpeg","_links":{"self":[{"href":"http:\/\/miguelpons.net\/english\/wp-json\/wp\/v2\/media\/495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/miguelpons.net\/english\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/miguelpons.net\/english\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/miguelpons.net\/english\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/miguelpons.net\/english\/wp-json\/wp\/v2\/comments?post=495"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":491,"href":"http:\/\/miguelpons.net\/english\/wp-json\/wp\/v2\/pages\/491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}